{"id":4599,"date":"2014-04-01T08:06:59","date_gmt":"2014-04-01T06:06:59","guid":{"rendered":"http:\/\/solartradex.com\/blog\/?p=4599"},"modified":"2023-06-19T22:13:06","modified_gmt":"2023-06-19T20:13:06","slug":"la-nueva-tarifa-electrica-luces-y-sombras-i","status":"publish","type":"post","link":"https:\/\/solartradex.com\/blog\/la-nueva-tarifa-electrica-luces-y-sombras-i\/","title":{"rendered":"Nueva tarifa el\u00e9ctrica: Precios Voluntarios al Peque\u00f1o Consumidor (PVPC) (I)"},"content":{"rendered":"<p>La nueva tarifa el\u00e9ctrica ya esta aqu\u00ed. El pasado viernes 28 de marzo el Consejo de Ministros aprob\u00f3 el <span style=\"text-decoration: underline;\"><span style=\"color: #800080;\"><a title=\"RD 216\/2014 Tarifa El\u00e9ctrica\" href=\"https:\/\/www.boe.es\/boe\/dias\/2014\/03\/29\/pdfs\/BOE-A-2014-3376.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #800080; text-decoration: underline;\">Real Decreto 216\/2014<\/span><\/a><\/span><\/span> , que regula el m\u00e9todo de c\u00e1lculo de los precios voluntarios para el peque\u00f1o consumidor (PVPC) de energ\u00eda el\u00e9ctrica, o lo que es lo mismo, el precio de la electricidad para la gran mayor\u00eda de los consumidores dom\u00e9sticos espa\u00f1oles.<\/p>\n<p>\u00bf Estamos de enhorabuena? \u00a0Pues eso dicen desde el Ministerio de Industria, Energ\u00eda y Turismo, ya que seg\u00fan palabras del propio ministro, esta nueva metodolog\u00eda de c\u00e1lculo supondr\u00e1 un importante ahorro cifrado en m\u00e1s de 300 millones de Euros al a\u00f1o para el conjunto de consumidores, a la vez que fomentar\u00e1 un incremento de la competencia en este segmento de mercado debido a que se facilita la entrada de nuevos comercializadores de referencia&#8230;. o sea que nos ha tocado la loter\u00eda.<\/p>\n<p>Algunos me llamar\u00e9is puntilloso, pero aqu\u00ed hay algo que no me cuadra&#8230;. \u00bf alguien ha escuchado a don Ignacio S\u00e1nchez \u00a0Gal\u00e1n o a don Eduardo Montes, presidentes de Iberdrola y UNESA respectivamente, quejarse de la nueva metodolog\u00eda de c\u00e1lculo?<\/p>\n<p>Yo no, y la verdad es que esta anomal\u00eda funcional me da mucho, pero que mucho que pensar&#8230;.<\/p>\n<p>En el art\u00edculo de esta semana repasaremos las principales caracter\u00edsticas de los nuevos Precios Voluntarios al Peque\u00f1o Consumidor ( de ahora en adelante PVPC), y la semana que viene abordaremos algunas posibles consecuencias a futuro que pueden derivarse, y que quiz\u00e1s justifiquen este extra\u00f1o silencio&#8230;<\/p>\n<p style=\"text-align: center;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-4620 aligncenter\" title=\"Tarifa Electrica SolarTradex\" src=\"https:\/\/solartradex.com\/blog\/wp-content\/uploads\/2014\/03\/Fotolia_48654155_XS.jpg\" alt=\"Tarifa El\u00e9ctrica SolarTradex\" width=\"291\" height=\"413\" srcset=\"https:\/\/solartradex.com\/blog\/wp-content\/uploads\/2014\/03\/Fotolia_48654155_XS.jpg 291w, https:\/\/solartradex.com\/blog\/wp-content\/uploads\/2014\/03\/Fotolia_48654155_XS-211x300.jpg 211w\" sizes=\"(max-width: 291px) 100vw, 291px\" \/><\/p>\n<p><!--more-->Y es que no me dir\u00e9is que no os extra\u00f1a esta nueva actitud del Oligopolio, todo el d\u00eda quej\u00e1ndose que si les recortan los ingresos a la distribuci\u00f3n, que si las renovables son las culpables del d\u00e9ficit de tarifa, que si el \u00a0ministro Montoro no cumple sus promesas, y un largo etc\u00e9tera de innumerables letan\u00edas, \u00a0y ahora resulta que les disminuyen los ingresos, aumenta la competencia y encima \u00bf no se quejan?<\/p>\n<p>Claro&#8230; los m\u00e1s entendidos me dir\u00e9is que poco les afecta a las grandes el\u00e9ctricas este cambio, ya que \u00a0de un lado, el ahorro inducido con la nueva metodolog\u00eda es consecuencia de la eliminaci\u00f3n de la coberturas financieras que se daban en las antiguas <span style=\"text-decoration: underline;\"><span style=\"color: #800080;\"><a title=\"Y le llaman mercado libre\u2026. Feliz a\u00f1o 2014!!!!\" href=\"https:\/\/solartradex.com\/blog\/y-le-llaman-mercado-libre-feliz-ano-2014\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #800080; text-decoration: underline;\">subastas CESUR<\/span><\/a><\/span><\/span>, en las que adem\u00e1s de las grandes el\u00e9ctricas, tambi\u00e9n participaban todo tipo de entidades financieras, y que de otro lado el margen comercial de los PVPC est\u00e1 reconocido y regulado; y es verdad; pero a\u00fan as\u00ed, hay algo que me huele mal&#8230; pero vayamos por partes.<\/p>\n<p><span style=\"line-height: 1.5;\">En primer lugar conviene recordar que este cambio <\/span><strong style=\"line-height: 1.5;\">s\u00f3lo afecta\u00a0<\/strong><span style=\"line-height: 1.5;\">a los consumidores de menos de 10 kW acogidos a la antigua Tarifa de \u00daltimo Recurso ( TUR), ahora PVPC. Esto es \u00a0a los 16,5 millones de consumidores que tienen contratado el suministro con una comercializadora de referencia.<\/span><\/p>\n<p>Si no sab\u00e9is si vuestro comercializador es de referencia o no, \u00a0pod\u00e9is chequear el siguiente listado de la CNMC en\u00a0el que se muestran todos los comercializadores activos clasificados en funci\u00f3n de si son de referencia o no.<\/p>\n<p><span style=\"line-height: 1.5;\">Y en segundo lugar debemos tener presente que la metodolog\u00eda de c\u00e1lculo de los PVPC, s\u00f3lo afecta a su componente de mercado ( precio de fabricaci\u00f3n de la energ\u00eda) de la tarifa el\u00e9ctrica . Recordad que las tarifa\u00a0el\u00e9ctrica ( me permito llamarle de esta manera para que todos nos entendamos, aunque su nombre correcto sea Precio Voluntario al Peque\u00f1o Consumidor), tiene una estructura bin\u00f3mica:<\/span><\/p>\n<p style=\"padding-left: 30px;\">&#x25aa;\u00a0\u00a0 <b>T\u00e9rmino de Potencia<\/b>: Cantidad fija expresada en \u20ac\/kW y a\u00f1o, que se corresponde con lo que pagamos por cada kW que tenemos contratado y que en cierto modo nos otorga el derecho a consumir energ\u00eda cuando la necesitamos. \u00a0Este precio viene regulado por Orden Ministerial ( T\u00e9rmino d Potencia de los Peajes de Acceso a las Redes).<\/p>\n<p style=\"padding-left: 30px;\">A este t\u00e9rmino de potencia \u00a0debemos sumar la cantidad de <strong>4 \u20ac\/kW contratado\u00a0y a\u00f1o<\/strong> en concepto del margen comercial reconocido a las \u00a0comercializadoras de referencia por el servicio prestado. Esto significa que el beneficio de las comercializadoras de referencia se convierte en un t\u00e9rmino fijo exclusivamente, muy en l\u00ednea a las \u00faltimas tendencias \u00a0de este Gobierno, que intenta una vez m\u00e1s asegurar sus ingresos, a costa de penalizar el ahorro energ\u00e9tico.<\/p>\n<p style=\"padding-left: 30px;\">&#x25aa;\u00a0\u00a0 <b>T\u00e9rmino de Energ\u00eda: <\/b>Cantidad expresada en \u20ac\/kWh y que se corresponde con el precio que pagamos por cada kWh que consumimos.<\/p>\n<p style=\"padding-left: 30px;\">Este t\u00e9rmino de energ\u00eda, a su vez tambi\u00e9n tiene dos sub-componentes; de un lado un t\u00e9rmino regulado tambi\u00e9n por Orden Ministerial ( T\u00e9rmino de Energ\u00eda de los\u00a0Peajes de Acceso a las Redes) y que se justifica como el coste de utilizaci\u00f3n de la red de distribuci\u00f3n para llevar la electricidad a nuestras casas; y una segundo t\u00e9rmino que se corresponde con la componente de mercado comentada anteriormente, y sobre la que afecta este cambio de metodolog\u00eda de c\u00e1lculo.<\/p>\n<p>Y ahora la pregunta del mill\u00f3n: <strong>\u00bfSupondr\u00e1 la nueva tarifa el\u00e9ctrica un ahorro para los consumidores espa\u00f1oles?<\/strong><\/p>\n<p>En el corto plazo <strong>estoy convencido que s\u00ed,<\/strong> sin lugar a dudas.<\/p>\n<p>Hasta ahora la componente de mercado, se fijaba trimestralmente a trav\u00e9s de las finiquitadas subastas CESUR, a las que acud\u00edan los 5 comercializadores de referencia para comprar la energ\u00eda que deb\u00edan suministrar a lo largo del siguiente trimestre.<\/p>\n<p>Esta energ\u00eda se la vend\u00edan una serie de intermediarios financieros, entre los que tambi\u00e9n se encontraban las mismas 5 grandes el\u00e9ctricas ( o sea que s\u00ed que se beneficiaban del sistema antiguo), que vend\u00edan la energ\u00eda a un precio fijo mediante un contrato por diferencias; esto es, si el precio real de la energ\u00eda que se negocia diariamente a nivel horario, era inferior al precio al que hab\u00edan cerrado la venta de energ\u00eda para todo el trimestre, entonces estos intermediarios ganaban la diferencia entre el precio de venta y el precio real de la energ\u00eda en el mercado diario, y si por el contrario el precio de la energ\u00eda era m\u00e1s alto de lo esperado entonces perd\u00edan dinero.<\/p>\n<p>El truco pues, era vender la energ\u00eda en la subasta CESUR lo m\u00e1s cara posible para cubrirse de los vaivenes del mercado diario, y de este modo asegurarse ping\u00fces beneficios&#8230;. tan ping\u00fces que en el informe que hizo la Comisi\u00f3n de los Mercados y la Competencia acerca de la nueva metodolog\u00eda de c\u00e1lculo de los PVPC, se estimaba que el coste impl\u00edcito de la energ\u00eda para el consumidor medio acogido a la Tarifa de \u00daltimo Recurso ( antiguo nombre del Precio Voluntario al Peque\u00f1o Consumidor), hab\u00eda sido de media, a lo largo de los 5 a\u00f1os de vigencia de las subastas CESUR, un 11% m\u00e1s caro que el precio del mercado diario&#8230; casi nada, 1.641 millones de Euros en 5 a\u00f1os.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-4611\" src=\"https:\/\/solartradex.com\/blog\/wp-content\/uploads\/2014\/03\/Captura-de-pantalla-2014-03-31-a-las-16.59.29.png\" alt=\"PVPC vs Mercado diario SolarTradex\" width=\"891\" height=\"384\" title=\"\" srcset=\"https:\/\/solartradex.com\/blog\/wp-content\/uploads\/2014\/03\/Captura-de-pantalla-2014-03-31-a-las-16.59.29.png 891w, https:\/\/solartradex.com\/blog\/wp-content\/uploads\/2014\/03\/Captura-de-pantalla-2014-03-31-a-las-16.59.29-300x129.png 300w\" sizes=\"(max-width: 891px) 100vw, 891px\" \/><\/p>\n<p>As\u00ed pues, con esta nueva metodolog\u00eda de c\u00e1lculo, desaparecen las subastas CESUR que fijaban el precio de la energ\u00eda para el trimestre siguiente, de modo que a partir de hoy d\u00eda 1 de abril, el precio de la energ\u00eda se fijar\u00e1 hora a hora en el mercado diario.<\/p>\n<p>De esta manera al desaparecer las subastas, desaparecen tambi\u00e9n las coberturas necesarias para garantizar un precio fijo, motivo por el que y seg\u00fan el hist\u00f3rico de los \u00faltimos 5 a\u00f1os, se espera que el precio de la energ\u00eda baje considerablemente.<\/p>\n<p>La principal ventaja de este m\u00e9todo es que adem\u00e1s de bajar el precio por el efecto de la supresi\u00f3n de las coberturas financieras, tambi\u00e9n permitir\u00e1 hacer gesti\u00f3n de la demanda, de modo que conociendo los precios de la energ\u00eda para cada hora ( se negocian con 24 horas de antelaci\u00f3n, y se podr\u00e1n consultar en la web de REE y OMIE), se podr\u00e1 \u00a0poner la lavadora en las horas en las que la energ\u00eda es m\u00e1s barata&#8230; sin ir m\u00e1s lejos, ma\u00f1ana 1 de abril del 2014, se espera que el precio de la energ\u00eda entre las 4 y las 7 de la ma\u00f1ana sea de 0,010 \u20ac\/kWh, mientras que a las 12 del mediod\u00eda ser\u00e1 de 0,033 \u20ac\/kWh.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-4613\" src=\"https:\/\/solartradex.com\/blog\/wp-content\/uploads\/2014\/03\/Captura-de-pantalla-2014-03-31-a-las-17.28.43.png\" alt=\"Precio mercado diario SolarTradex\" width=\"817\" height=\"363\" title=\"\" srcset=\"https:\/\/solartradex.com\/blog\/wp-content\/uploads\/2014\/03\/Captura-de-pantalla-2014-03-31-a-las-17.28.43.png 817w, https:\/\/solartradex.com\/blog\/wp-content\/uploads\/2014\/03\/Captura-de-pantalla-2014-03-31-a-las-17.28.43-300x133.png 300w\" sizes=\"(max-width: 817px) 100vw, 817px\" \/><\/p>\n<p>Y finalmente hay otra gran novedad que seg\u00fan palabras del propio ministro, deber\u00eda servir para fomentar una mayor competencia, y es que\u00a0se abre la puerta a la entrada de nuevos comercializadores de referencia, que hasta la fecha eran tan s\u00f3lo cinco.<\/p>\n<p>Estos nuevos aspirantes a nuevos comercializadores de referencia deber\u00e1n demostrar haber tenido una media de m\u00e1s de 25.000 clientes \u00a0durante los \u00faltimos 3 a\u00f1os. Este hecho en principio deber\u00eda fomentar una mayor competencia, aunque yo me pregunto&#8230; \u00bf como se fomenta una mayor competencia si todos los comercializadores de referencia van a vender al mismo precio? El \u00fanico sitio en el que hay margen es en los 4 \u20ac\/kW y a\u00f1o que se han estipulado como remuneraci\u00f3n comercial, y la verdad no creo que las diferencias entre comercializadores en este cap\u00edtulo, sean lo suficientemente significativas como para aumentar la competencia de manera significativa.<\/p>\n<p>Hasta este punto, las noticias m\u00e1s o menos positivas&#8230; veamos \u00a0ahora algunos puntos d\u00e9biles de la propuesta.<\/p>\n<p>En primer lugar este nuevo modo de fijar el precio de la energ\u00eda, supondr\u00e1 cierta volatilidad en los precios, de manera que ser\u00e1 imposible saber con antelaci\u00f3n el precio que pagaremos por los kWh que consumamos a los largo del pr\u00f3ximo trimestre.<\/p>\n<p>Es cierto que se obliga a los comercializadores de referencia a tener disponible, una oferta a precio fijo durante 12 meses para aquellos consumidores que no quieran estar sujetos a esta volatilidad, pero en este caso, y como es l\u00f3gico, el precio conllevar\u00e1 de nuevo una cobertura por lo que ser\u00e1 significativamente m\u00e1s caro.<\/p>\n<p>Mi recomendaci\u00f3n personal: <strong>acogerse al precio variable.<\/strong><\/p>\n<p>Y en segundo lugar, \u00a0debemos saber que tan s\u00f3lo hay instalados en Espa\u00f1a, unos 7 millones de contadores \u00abinteligentes\u00bb( sobre un parque de unos 26 millones de contadores) que permitan la gesti\u00f3n de la demanda, esto es telemedir el consumo real que estamos realizando cada hora y por lo tanto facturar el precio horario. Y adem\u00e1s la gran mayor\u00eda de estos 7 millones de contadores no est\u00e1n \u00a0interconectados con el sistema, por lo que todav\u00eda no pueden enviar los datos de consumo horarios y por lo tanto es como si no estuvieran instalados.<\/p>\n<p>Mientras tanto, a todos los consumidores a los que no se les pueda telemedir ,se les facturar\u00e1 seg\u00fan un perfil de consumo diario del consumidor tipo que nos definir\u00e1 semanalmente Red El\u00e9ctrica, y por lo tanto, estos consumidores no podr\u00e1n gestionar de manera eficiente el\u00a0consumo.<\/p>\n<p>\u00bfHasta cuando? En principio la fecha l\u00edmite para sustituir la totalidad de contadores es el 31 de diciembre del 2018&#8230;. a\u00fan as\u00ed nos veremos beneficiados por la disminuci\u00f3n del precio debido a la eliminaci\u00f3n de las subastas CESUR.<\/p>\n<p>Hoy lo dejamos en en este punto, y la semana que viene retomaremos la cuesti\u00f3n planteando algunas de mis oscuras teor\u00edas conspiratorias &#8230; \u00bf Por qu\u00e9 no se ha quejado el Oligopolio de este cambio?<\/p>\n<p>Hasta la semana que viene!!!!<\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;4599&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Valora este post&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 votos)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;Nueva tarifa el\u00e9ctrica: Precios Voluntarios al Peque\u00f1o Consumidor (PVPC) (I)&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            <span class=\"kksr-muted\">Valora este post<\/span>\n    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>La nueva tarifa el\u00e9ctrica ya esta aqu\u00ed. El pasado viernes 28 de marzo el Consejo de Ministros aprob\u00f3 el Real Decreto 216\/2014 , que regula el m\u00e9todo de c\u00e1lculo de los precios voluntarios para el peque\u00f1o consumidor (PVPC) de energ\u00eda el\u00e9ctrica, o lo que es lo mismo, el precio de la electricidad para la gran &hellip; <a href=\"https:\/\/solartradex.com\/blog\/la-nueva-tarifa-electrica-luces-y-sombras-i\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">Nueva tarifa el\u00e9ctrica: Precios Voluntarios al Peque\u00f1o Consumidor (PVPC) (I)<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_mbp_gutenberg_autopost":false,"footnotes":""},"categories":[115],"tags":[],"class_list":["post-4599","post","type-post","status-publish","format-standard","hentry","category-tarifas-electricas"],"fimg_url":false,"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/solartradex.com\/blog\/wp-json\/wp\/v2\/posts\/4599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solartradex.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/solartradex.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/solartradex.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/solartradex.com\/blog\/wp-json\/wp\/v2\/comments?post=4599"}],"version-history":[{"count":2,"href":"https:\/\/solartradex.com\/blog\/wp-json\/wp\/v2\/posts\/4599\/revisions"}],"predecessor-version":[{"id":7175,"href":"https:\/\/solartradex.com\/blog\/wp-json\/wp\/v2\/posts\/4599\/revisions\/7175"}],"wp:attachment":[{"href":"https:\/\/solartradex.com\/blog\/wp-json\/wp\/v2\/media?parent=4599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/solartradex.com\/blog\/wp-json\/wp\/v2\/categories?post=4599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/solartradex.com\/blog\/wp-json\/wp\/v2\/tags?post=4599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}